{"id":1,"name":"admin","url":"http:\/\/postelnoe.in.net","description":"","link":"https:\/\/postelnoe.in.net\/index.php\/author\/admin\/","slug":"admin","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7932b2e116b076a54f452848eaabd5857f61bd957fe8a218faf216f24c9885bb?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7932b2e116b076a54f452848eaabd5857f61bd957fe8a218faf216f24c9885bb?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7932b2e116b076a54f452848eaabd5857f61bd957fe8a218faf216f24c9885bb?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/postelnoe.in.net\/index.php\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/postelnoe.in.net\/index.php\/wp-json\/wp\/v2\/users"}]}}